{"id":476,"date":"2019-06-06T01:11:48","date_gmt":"2019-06-05T23:11:48","guid":{"rendered":"http:\/\/cryanim.vetagro-sup.fr\/?page_id=476"},"modified":"2023-07-06T07:49:21","modified_gmt":"2023-07-06T05:49:21","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9 \/ RGPD"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"476\" class=\"elementor elementor-476\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-600a69e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"600a69e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64bccd6a\" data-id=\"64bccd6a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e71d699 elementor-widget elementor-widget-text-editor\" data-id=\"e71d699\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400; text-align: justify;\">\u00a0La pr\u00e9sente politique de confidentialit\u00e9 d\u00e9finit et vous informe de la mani\u00e8re dont VetAgro Sup\u00a0 (ci-apr\u00e8s\u00a0<span style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400;\">le\u00a0<\/span><span style=\"font-size: 15.3px;\">\u00ab Propri\u00e9taire du Site \u00bb) utilise et prot\u00e8ge les informations que l\u2019Utilisateur transmet, le cas \u00e9ch\u00e9ant, lorsqu\u2019il utilise le site accessible \u00e0 partir de l\u2019URL suivante :\u00a0<\/span><a style=\"background-color: #ffffff; font-size: 15.3px;\" href=\"http:\/\/cryanim.vetagro-sup.fr\/\">cryanim.vetagro-sup.fr<\/a><span style=\"font-size: 15.3px;\">\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). Cette politique de confidentialit\u00e9 compl\u00e8te les mentions l\u00e9gales et les Conditions G\u00e9n\u00e9rales d&rsquo;Utilisation que l&rsquo;utilisateur peut consulter \u00e0 l&rsquo;adresse suivante :\u00a0<\/span><a style=\"background-color: #ffffff; font-size: 15.3px;\" href=\"http:\/\/cryanim.vetagro-sup.fr\/index.php\/mentions-legales\/\">http:\/\/cryanim.vetagro-sup.fr\/index.php\/mentions-legales\/<\/a>.<\/p>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400; text-align: justify;\">Veuillez noter que cette politique de confidentialit\u00e9 est susceptible d\u2019\u00eatre modifi\u00e9e ou compl\u00e9t\u00e9e \u00e0 tout moment, notamment en vue de se conformer \u00e0 toute \u00e9volution l\u00e9gislative, r\u00e9glementaire, jurisprudentielle ou technologique. Dans un tel cas, la date de sa mise \u00e0 jour sera clairement identifi\u00e9e en t\u00eate de la pr\u00e9sente politique. Ces modifications engagent l\u2019utilisateur d\u00e8s leur mise en ligne. Il convient par cons\u00e9quent que l\u2019utilisateur consulte r\u00e9guli\u00e8rement la pr\u00e9sente politique de confidentialit\u00e9 et d\u2019utilisation des cookies afin de prendre connaissance de ses \u00e9ventuelles modifications.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4f9c2 elementor-widget elementor-widget-heading\" data-id=\"bb4f9c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Donn\u00e9es personnelles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f27d339 elementor-widget elementor-widget-text-editor\" data-id=\"1f27d339\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p>En France, les donn\u00e9es personnelles sont notamment prot\u00e9g\u00e9es par la loi n\u00b0\u00a078-87 du 6 janvier 1978, la loi n\u00b0\u00a02004-801 du 6 ao\u00fbt 2004, l\u2019article L.\u00a0226-13 du Code p\u00e9nal et la Directive Europ\u00e9enne du 24 octobre 1995.<\/p>\n<p>D\u2019une mani\u00e8re g\u00e9n\u00e9rale, il vous est possible de visiter le Site sans communiquer aucune information personnelle vous concernant. En toute hypoth\u00e8se, vous n\u2019\u00eates en aucune mani\u00e8re oblig\u00e9 de transmettre ces informations au Propri\u00e9taire du Site.<\/p>\n<p>N\u00e9anmoins, en cas de refus, il se peut que vous ne puissiez pas b\u00e9n\u00e9ficier de certaines informations ou services que vous avez demand\u00e9s. A ce titre en effet, le Propri\u00e9taire du Site peut \u00eatre amen\u00e9 dans certains cas \u00e0 vous demander de renseigner vos \u00ab\u00a0nom, pr\u00e9nom, adresse postale, adresse mail, num\u00e9ro de t\u00e9l\u00e9phone, entreprise et fonction et autres informations\u00a0\u00bb vous concernant (ci-apr\u00e8s vos \u00ab Informations Personnelles \u00bb). En fournissant ces informations, vous acceptez express\u00e9ment qu\u2019elles soient trait\u00e9es par le Propri\u00e9taire du Site, aux fins indiqu\u00e9es au point 2 ci-dessous ainsi qu\u2019aux fins \u00e9ventuellement rappel\u00e9es \u00e0 la fin des formulaires.<\/p>\n<p class=\"p-bis\">En tout \u00e9tat de cause, aucune information personnelle de l\u2019utilisateur du Site n\u2019est\u00a0:<\/p>\n<ul>\n<li>collect\u00e9e \u00e0 l\u2019insu de l\u2019utilisateur\u00a0;<\/li>\n<li>publi\u00e9e \u00e0 l\u2019insu de l\u2019utilisateur\u00a0;<\/li>\n<li>\u00e9chang\u00e9e, transf\u00e9r\u00e9e, c\u00e9d\u00e9e ou vendue sur un support quelconque \u00e0 des tiers.<\/li>\n<\/ul>\n<p>Conform\u00e9ment au R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (<i>General Data Protection R\u00e9gulation<\/i>) adopt\u00e9 par le Parlement europ\u00e9en le 14 avril 2016, et \u00e0 la Loi Informatique et Libert\u00e9s du 6 janvier 1978 modifi\u00e9e, VetAgro Sup vous informe des points suivants\u00a0:<\/p>\n<h3 class=\"wp-block-heading\">1. Identit\u00e9 du responsable du traitement des donn\u00e9es et d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/h3>\n<p>Le responsable du traitement est le Propri\u00e9taire du Site dont les coordonn\u00e9es sont indiqu\u00e9es \u00e0 l&rsquo;adresse suivante\u00a0: <a href=\"https:\/\/www.vetagro-sup.fr\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.vetagro-sup.fr\/<\/a>.<\/p>\n<blockquote>\n<p>Le responsable du traitement des donn\u00e9es est charg\u00e9 de d\u00e9terminer les finalit\u00e9s et les moyens mis au service du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel.<br \/>Le responsable du traitement s&rsquo;engage \u00e0 prot\u00e9ger les donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es, \u00e0 ne pas\u00a0les transmettre \u00e0 des tiers sans que l&rsquo;Utilisateur n&rsquo;en ait \u00e9t\u00e9 inform\u00e9 et \u00e0 respecter les finalit\u00e9s pour\u00a0lesquelles ces donn\u00e9es ont \u00e9t\u00e9 collect\u00e9es.\u00a0<br \/>De plus, le responsable du traitement des donn\u00e9es s&rsquo;engage \u00e0 notifier l&rsquo;utilisateur en cas de rectification\u00a0ou de suppression des donn\u00e9es, \u00e0 moins que cela n&rsquo;entra\u00eene pour lui des formalit\u00e9s, co\u00fbts et d\u00e9marches\u00a0disproportionn\u00e9s.\u00a0Dans le cas o\u00f9 l&rsquo;int\u00e9grit\u00e9, la confidentialit\u00e9 ou la s\u00e9curit\u00e9 des donn\u00e9es \u00e0 caract\u00e8re personnel de l&rsquo;utilisateur\u00a0est compromise, le responsable du traitement s&rsquo;engage \u00e0 informer l&rsquo;utilisateur par tout moyen.<\/p>\n<\/blockquote>\n<p>Le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es est Mr <a href=\"mailto:dpo@vetagro-sup.fr\">Cl\u00e9ment DUTRONCY<\/a>.<\/p>\n<blockquote>\n<p>Le r\u00f4le du D\u00e9l\u00e9gu\u00e9 \u00e0 la Protection des Donn\u00e9es est de s&rsquo;assurer la bonne mise en oeuvre des dispositions nationales et supranationales relatives \u00e0 la collecte et au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel. Il est parfois appel\u00e9 DPO (pour <em>Data Protection Officer<\/em>).<\/p>\n<\/blockquote>\n<h3>2. Finalit\u00e9s du traitement<\/h3>\n<p>Le Propri\u00e9taire du Site est susceptible de traiter vos Informations Personnelles :<\/p>\n<blockquote>\n<ul>\n<li><span style=\"font-size: 15.3px;\">aux fins de vous fournir les informations ou les services que vous avez demand\u00e9;<\/span><\/li>\n<li><span style=\"font-size: 15.3px;\">aux fins de recueillir des informations nous permettant d\u2019am\u00e9liorer le Site, les produits et services (notamment par le biais de cookies);<\/span><\/li>\n<li><span style=\"font-size: 15.3px;\">aux fins de pouvoir vous contacter \u00e0 propos de diff\u00e9rents \u00e9v\u00e9nements relatifs \u00e0 la relation client.<\/span><\/li>\n<\/ul>\n<\/blockquote>\n<h3>3. Destinataires<\/h3>\n<p>Seul le Propri\u00e9taire du Site est destinataire de vos Informations Personnelles. Celles-ci, que ce soit sous forme individuelle ou agr\u00e9g\u00e9e, ne sont jamais transmises \u00e0 un tiers, nonobstant les sous-traitants auxquels le Propri\u00e9taire du Site fait appel (vous trouverez de plus amples informations \u00e0 leur sujet au point 8 ci-dessous). Ni le Propri\u00e9taire du Site, ni l\u2019un quelconque de ses sous-traitants, ne proc\u00e8dent \u00e0 la commercialisation des donn\u00e9es personnelles des visiteurs et utilisateurs de son Site.<\/p>\n<h3>4. Dur\u00e9e de conservation<\/h3>\n<p>Vos Informations Personnelles sont conserv\u00e9es par le Propri\u00e9taire du Site uniquement pour le temps correspondant \u00e0 la finalit\u00e9 de la collecte telle qu\u2019indiqu\u00e9e en 2 ci-dessus, qui ne saurait en tout \u00e9tat de cause exc\u00e9der les limites impos\u00e9es par la loi.<\/p>\n<p>Toutefois, si vous laissez un commentaire sur le Site, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p>\n<h3>5. Droits Informatique et Libert\u00e9s<\/h3>\n<p>Vous disposez des droits suivants concernant vos Informations Personnelles, que vous pouvez exercer en nous \u00e9crivant \u00e0 l\u2019adresse postale mentionn\u00e9e sur le Site ou en remplissant le <a href=\"http:\/\/cryanim.vetagro-sup.fr\/index.php\/contact\/\" target=\"_blank\" rel=\"noopener\">formulaire de contact<\/a> du Site.\u00a0<span style=\"font-size: 15.3px;\">Afin que le responsable du traitement des donn\u00e9es fasse droit \u00e0 sa demande, l&rsquo;Utilisateur est tenu de lui communiquer son nom ou sa raison sociale, ses coordonn\u00e9es physiques et\/ou \u00e9lectroniques, ainsi que le cas \u00e9ch\u00e9ant la r\u00e9f\u00e9rence dont il disposerait en tant qu\u2019utilisateur du Site.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11a3c42 elementor-widget elementor-widget-accordion\" data-id=\"11a3c42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1841\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1841\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Droit d\u2019acc\u00e8s et de communication des donn\u00e9es<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1841\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1841\"><p>Vous avez la facult\u00e9 d\u2019acc\u00e9der aux Informations Personnelles qui vous concernent.<\/p>\n<p>Cependant, en raison de l\u2019obligation de s\u00e9curit\u00e9 et de confidentialit\u00e9 dans le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel qui incombe au Propri\u00e9taire du Site, vous \u00eates inform\u00e9 que votre demande sera trait\u00e9e sous r\u00e9serve que vous rapportiez la preuve de votre identit\u00e9, notamment par la production d\u2019un scan de votre titre d\u2019identit\u00e9 valide (en cas de demande par notre formulaire ou d\u2019une photocopie sign\u00e9e de votre titre d\u2019identit\u00e9 valide (en cas de demande adress\u00e9e par \u00e9crit).<\/p>\n<p>Le Propri\u00e9taire du Site vous informe qu\u2019il sera en droit, le cas \u00e9ch\u00e9ant, de s\u2019opposer aux demandes manifestement abusives (de par leur nombre, leur caract\u00e8re r\u00e9p\u00e9titif ou syst\u00e9matique).<\/p>\n<p>Pour vous aider dans votre d\u00e9marche, notamment si vous d\u00e9sirez exercer votre droit d\u2019acc\u00e8s par le biais d\u2019une demande \u00e9crite \u00e0 l\u2019adresse postale mentionn\u00e9e au point 1, vous trouverez en cliquant sur le lien suivant un mod\u00e8le de courrier \u00e9labor\u00e9 par la Commission Nationale de l\u2019Informatique et des Libert\u00e9s (la \u00ab CNIL \u00bb).<\/p>\n<p><a href=\"https:\/\/www.cnil.fr\/fr\/modele\/courrier\/exercer-son-droit-dacces\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cnil.fr\/fr\/modele\/courrier\/exercer-son-droit-dacces<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1842\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1842\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Droit de modification des donn\u00e9es<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1842\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1842\"><p>Au titre de ce droit, la l\u00e9gislation vous habilite \u00e0 demander la rectification, la mise \u00e0 jour, le verrouillage ou encore l\u2019effacement des donn\u00e9es vous concernant qui peuvent s\u2019av\u00e9rer le cas \u00e9ch\u00e9ant inexactes, erron\u00e9es, incompl\u00e8tes ou obsol\u00e8tes.<\/p>\n<p>Pour vous aider dans votre d\u00e9marche, notamment si vous d\u00e9sirez exercer votre droit de rectification par le biais d\u2019une demande \u00e9crite \u00e0 l\u2019adresse postale mentionn\u00e9e sur le Site, vous trouverez en cliquant sur le lien suivant un mod\u00e8le de courrier \u00e9labor\u00e9 par la CNIL.<\/p>\n<p><a href=\"https:\/\/www.cnil.fr\/fr\/modele\/courrier\/rectifier-des-donnees-inexactes-obsoletes-ou-perimees\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cnil.fr\/fr\/modele\/courrier\/rectifier-des-donnees-inexactes-obsoletes-ou-perimees<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1843\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1843\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Droit d'opposition<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1843\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1843\"><p>L\u2019exercice de ce droit n\u2019est possible que dans l\u2019une des deux situations suivantes :<\/p>\n<ul>\n<li>lorsque l\u2019exercice de ce droit est fond\u00e9 sur des motifs l\u00e9gitimes;<\/li>\n<li>lorsque l\u2019exercice de ce droit vise \u00e0 faire obstacle \u00e0 ce que les donn\u00e9es recueillies soient utilis\u00e9es \u00e0 des fins de prospection commerciale.<\/li>\n<\/ul>\n<p>Pour vous aider dans votre d\u00e9marche, notamment si vous d\u00e9sirez exercer votre droit d\u2019opposition par le biais d\u2019une demande \u00e9crite adress\u00e9e \u00e0 l\u2019adresse postale indiqu\u00e9e sur le Site, vous trouverez en cliquant sur le lien suivant un mod\u00e8le de courrier \u00e9labor\u00e9 par la CNIL.<\/p>\n<p><a href=\"https:\/\/www.cnil.fr\/fr\/modele\/courrier\/supprimer-des-informations-vous-concernant-dun-site-internet\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cnil.fr\/fr\/modele\/courrier\/supprimer-des-informations-vous-concernant-dun-site-internet<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1844\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1844\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Droit de d\u00e9terminer le sort des donn\u00e9es apr\u00e8s la mort<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1844\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1844\"><p>Il est rappel\u00e9 \u00e0 l\u2019utilisateur qu\u2019il peut organiser quel doit \u00eatre le devenir de ses donn\u00e9es collect\u00e9es et trait\u00e9es s\u2019il d\u00e9c\u00e8de, conform\u00e9ment \u00e0 la loi n\u20192016\u00b7 1321 du 7 octobre 2016.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1fd6a7 elementor-widget elementor-widget-text-editor\" data-id=\"b1fd6a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 17.595px; font-style: normal; text-align: justify;\">6. D\u00e9lais de r\u00e9ponse<\/h3>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400; text-align: justify;\">Le Propri\u00e9taire du Site s\u2019engage \u00e0 r\u00e9pondre \u00e0 votre demande d\u2019acc\u00e8s, de rectification ou d\u2019opposition ou toute autre demande compl\u00e9mentaire d\u2019informations dans un d\u00e9lai raisonnable qui ne saurait d\u00e9passer 1\u00a0mois \u00e0 compter de la r\u00e9ception de votre demande.<\/p>\n<h3 style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 17.595px; font-style: normal; text-align: justify;\">7. Donn\u00e9es personnelles des personnes mineures<\/h3>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400; text-align: justify;\">Conform\u00e9ment aux dispositions de l&rsquo;article 8 du r\u00e8glement europ\u00e9en 2016\/679 et \u00e0 la loi Informatique et Libert\u00e9s, seuls les mineurs \u00e2g\u00e9s de 15 ans ou plus peuvent consentir au traitement de leurs donn\u00e9es personnelles. Si l&rsquo;utilisateur est un mineur de moins de 15\u00a0ans, l&rsquo;accord d&rsquo;un repr\u00e9sentant l\u00e9gal sera requis afin que des donn\u00e9es \u00e0 caract\u00e8re personnel puissent \u00eatre collect\u00e9es et trait\u00e9es. Le Propri\u00e9taire du Site se r\u00e9serve le droit de v\u00e9rifier par tout moyen que l&rsquo;utilisateur est \u00e2g\u00e9 de plus de 15 ans, ou qu&rsquo;il aura obtenu l&rsquo;accord d&rsquo;un repr\u00e9sentant l\u00e9gal avant de naviguer sur le Site.<\/p>\n<h3 style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 17.595px; font-style: normal; text-align: justify;\">8. Transmission des donn\u00e9es \u00e0 des tiers<\/h3>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400; text-align: justify;\">Les donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es par le Site ne sont transmises \u00e0 aucun tiers, et ne sont trait\u00e9es que par le Propri\u00e9taire du Site. Toutefois, les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n<h3 style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 17.595px; font-style: normal;\">9. Information de l&rsquo;utilisateur en cas de faille de s\u00e9curit\u00e9 d\u00e9cel\u00e9e par le Propri\u00e9taire du Site<\/h3>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400;\">Nous nous engageons \u00e0 mettre en \u0153uvre toutes les mesures techniques et organisationnelles appropri\u00e9es afin de garantir un niveau de s\u00e9curit\u00e9 adapt\u00e9 au regard des risques d&rsquo;acc\u00e8s accidentels, non autoris\u00e9s ou ill\u00e9gaux, de divulgation, d&rsquo;alt\u00e9ration, de perte ou encore de destruction des donn\u00e9es personnelles vous concernant. Dans l&rsquo;\u00e9ventualit\u00e9 o\u00f9 nous prendrions connaissance d&rsquo;un acc\u00e8s ill\u00e9gal aux donn\u00e9es personnelles vous concernant stock\u00e9es sur nos serveurs ou ceux de nos prestataires, ou d&rsquo;un acc\u00e8s non autoris\u00e9 ayant pour cons\u00e9quence la r\u00e9alisation des risques identifi\u00e9s ci-dessus, nous nous engageons \u00e0\u00a0:<\/p>\n<ul style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400;\">\n<li style=\"font-size: 15.3px;\">vous notifier l&rsquo;incident dans les plus brefs d\u00e9lais\u00a0;<\/li>\n<li style=\"font-size: 15.3px;\">examiner les causes de l&rsquo;incident et vous en informer\u00a0;<\/li>\n<li style=\"font-size: 15.3px;\">prendre les mesures n\u00e9cessaires dans la limite du raisonnable afin d&rsquo;amoindrir les effets n\u00e9gatifs et pr\u00e9judices pouvant r\u00e9sulter dudit incident.<\/li>\n<\/ul>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; font-family: Roboto, sans-serif; font-size: 15.3px; font-style: normal; font-weight: 400;\">En aucun cas les engagements d\u00e9finis au point pr\u00e9sent relatifs \u00e0 la notification en cas de faille de s\u00e9curit\u00e9 ne peuvent \u00eatre assimil\u00e9s \u00e0 une quelconque reconnaissance de faute ou de responsabilit\u00e9 quant \u00e0 la survenance de l&rsquo;incident en question.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a0La pr\u00e9sente politique de confidentialit\u00e9 d\u00e9finit et vous informe de la mani\u00e8re dont VetAgro Sup\u00a0 (ci-apr\u00e8s\u00a0le\u00a0\u00ab Propri\u00e9taire du Site \u00bb) utilise et prot\u00e8ge les informations que l\u2019Utilisateur transmet, le cas \u00e9ch\u00e9ant, lorsqu\u2019il utilise le site accessible \u00e0 partir de l\u2019URL suivante :\u00a0cryanim.vetagro-sup.fr\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). Cette politique de confidentialit\u00e9 compl\u00e8te les mentions l\u00e9gales et [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-476","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 \/ RGPD - CRB CryAnim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 \/ RGPD - CRB CryAnim\" \/>\n<meta property=\"og:description\" content=\"\u00a0La pr\u00e9sente politique de confidentialit\u00e9 d\u00e9finit et vous informe de la mani\u00e8re dont VetAgro Sup\u00a0 (ci-apr\u00e8s\u00a0le\u00a0\u00ab Propri\u00e9taire du Site \u00bb) utilise et prot\u00e8ge les informations que l\u2019Utilisateur transmet, le cas \u00e9ch\u00e9ant, lorsqu\u2019il utilise le site accessible \u00e0 partir de l\u2019URL suivante :\u00a0cryanim.vetagro-sup.fr\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). Cette politique de confidentialit\u00e9 compl\u00e8te les mentions l\u00e9gales et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"CRB CryAnim\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VetAgroSup\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T05:49:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/index.php\\\/politique-de-confidentialite\\\/\",\"url\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/index.php\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 \\\/ RGPD - CRB CryAnim\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/#website\"},\"datePublished\":\"2019-06-05T23:11:48+00:00\",\"dateModified\":\"2023-07-06T05:49:21+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/index.php\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9 \\\/ RGPD\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/#website\",\"url\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/\",\"name\":\"CRB CryAnim\",\"description\":\"Conservons d\u00e8s aujourd\u2019hui les ressources de notre avenir\",\"publisher\":{\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/#organization\",\"name\":\"CRB CryAnim\",\"url\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Logo-CRB-fond-clair.png\",\"contentUrl\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Logo-CRB-fond-clair.png\",\"width\":5756,\"height\":1689,\"caption\":\"CRB CryAnim\"},\"image\":{\"@id\":\"http:\\\/\\\/cryanim.vetagro-sup.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VetAgroSup\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/vetagrosup---campus-v-t-rinaire-de-lyon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 \/ RGPD - CRB CryAnim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 \/ RGPD - CRB CryAnim","og_description":"\u00a0La pr\u00e9sente politique de confidentialit\u00e9 d\u00e9finit et vous informe de la mani\u00e8re dont VetAgro Sup\u00a0 (ci-apr\u00e8s\u00a0le\u00a0\u00ab Propri\u00e9taire du Site \u00bb) utilise et prot\u00e8ge les informations que l\u2019Utilisateur transmet, le cas \u00e9ch\u00e9ant, lorsqu\u2019il utilise le site accessible \u00e0 partir de l\u2019URL suivante :\u00a0cryanim.vetagro-sup.fr\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). Cette politique de confidentialit\u00e9 compl\u00e8te les mentions l\u00e9gales et [&hellip;]","og_url":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/","og_site_name":"CRB CryAnim","article_publisher":"https:\/\/www.facebook.com\/VetAgroSup\/","article_modified_time":"2023-07-06T05:49:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/","url":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 \/ RGPD - CRB CryAnim","isPartOf":{"@id":"http:\/\/cryanim.vetagro-sup.fr\/#website"},"datePublished":"2019-06-05T23:11:48+00:00","dateModified":"2023-07-06T05:49:21+00:00","breadcrumb":{"@id":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/cryanim.vetagro-sup.fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9 \/ RGPD"}]},{"@type":"WebSite","@id":"http:\/\/cryanim.vetagro-sup.fr\/#website","url":"http:\/\/cryanim.vetagro-sup.fr\/","name":"CRB CryAnim","description":"Conservons d\u00e8s aujourd\u2019hui les ressources de notre avenir","publisher":{"@id":"http:\/\/cryanim.vetagro-sup.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/cryanim.vetagro-sup.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/cryanim.vetagro-sup.fr\/#organization","name":"CRB CryAnim","url":"http:\/\/cryanim.vetagro-sup.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/cryanim.vetagro-sup.fr\/#\/schema\/logo\/image\/","url":"http:\/\/cryanim.vetagro-sup.fr\/wp-content\/uploads\/2019\/05\/Logo-CRB-fond-clair.png","contentUrl":"http:\/\/cryanim.vetagro-sup.fr\/wp-content\/uploads\/2019\/05\/Logo-CRB-fond-clair.png","width":5756,"height":1689,"caption":"CRB CryAnim"},"image":{"@id":"http:\/\/cryanim.vetagro-sup.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VetAgroSup\/","https:\/\/www.linkedin.com\/school\/vetagrosup---campus-v-t-rinaire-de-lyon\/"]}]}},"_links":{"self":[{"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/pages\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":21,"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/pages\/476\/revisions"}],"predecessor-version":[{"id":2800,"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/pages\/476\/revisions\/2800"}],"wp:attachment":[{"href":"http:\/\/cryanim.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/media?parent=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}